{"id":50372,"date":"2024-03-20T18:08:39","date_gmt":"2024-03-20T16:08:39","guid":{"rendered":"https:\/\/electricsun.de\/shop\/electricsun-ionski-susilec-za-lase-1875-w-3-nastavitve-toplote-in-2-hitrosti-s-senzorjem-na-dotik-crn\/"},"modified":"2025-10-30T11:00:32","modified_gmt":"2025-10-30T09:00:32","slug":"ionski-susilnik-za-lase-electricsun-crn","status":"publish","type":"product","link":"https:\/\/electricsun.de\/sl\/trgovina\/ionski-susilnik-za-lase-electricsun-crn\/","title":{"rendered":"Ionski su\u0161ilnik za lase, ElectricSun Black, crn, 3 nastavitve toplote in 2 hitrosti, s senzorjem na dotik, 1875 W"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<h2>Prednosti Ionski su\u0161ilnik za lase, ElectricSun Black:<\/h2>\n<div class=\"left-lft-desc\">\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"Uscator par ElectricSun, feon cu ioni\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/hairdryer.svg\" alt=\"Uscator par ElectricSun, feon cu ioni\" width=\"40\" height=\"40\" \/><\/h6>\n<p>Hitro su\u0161enje brez po\u0161kodb las, s 3 nastavitvami toplote in 2 nastavitvami hitrosti, vro\u010dim zrakom 1875 W\/1200 W in hladnim zrakom 300 W. Hitrost zraka: 18 m\/s.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/ionization.svg\" width=\"40\" height=\"40\" \/><\/h6>\n<p>ANION &#8211; ionizacija, 200 milijonov negativnih ionov.<\/p>\n<\/div>\n<div class=\"right-rht-desc\">\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/motion-sensor.svg\" alt=\"\" width=\"40\" height=\"40\" \/><\/h6>\n<p>Inteligentni senzor dotika ima funkcijo prepoznavanja roke in se ustavi, ko ga spustite.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/touchscreen.svg\" alt=\"\" width=\"40\" height=\"40\" \/><\/h6>\n<p>Prikaz mo\u010di in hitrosti na ro\u010daju.<\/p>\n<\/div>\n<div style=\"clear: both;\"><\/div>\n<div class=\"center-cer-desc\">\n<p>Za vsako zavidanja vredno pri\u010desko se skriva visokokakovosten su\u0161ilec za lase. Ne glede na to, ali si \u017eelite \u017eivahnih kodrov, gladkih in sijo\u010dih las ali pa \u017eelite imeti v hipu suhe lase, je su\u0161ilnik las z ionizacijo ElectricSun idealna izbira.<\/p>\n<p>Ustvarite svoj slog z nadzorovanim pretokom zraka pri optimalni hitrosti.<\/p>\n<p>S hitrim motorjem za hitro su\u0161enje in ionsko tehnologijo z 200 milijoni negativnih ionov, ki prepre\u010dujejo elektrifikacijo in nadzorujejo nakodranost, fen za kosu ElectricSun v nekaj minutah poskrbi za gladko pri\u010desko. Vro\u010da nastavitev je namenjena ne\u017enemu in posko\u010dnemu su\u0161enju, hladna nastavitev pa pomaga dose\u010di \u017eeleno pri\u010desko.<\/p>\n<p>Poleg tega senzor na dotik, ergonomska oblika in majhna te\u017ea omogo\u010dajo udobno uporabo, napajalni kabel pa je idealne dol\u017eine za enostavno uporabo. Zaradi \u0161obe za koncentriranje zraka in zanke za obe\u0161anje je model enostaven za uporabo in shranjevanje.<\/p>\n<p>Ionski su\u0161ilnik za lase ElectricSun je izdelan iz visokokakovostnega materiala ABS z vhodom iz nerjave\u010dega jekla in sistemom za za\u0161\u010dito pred pregrevanjem. To je su\u0161ilnik za lase z motorjem s 110 000 vrtljaji na minuto za doma\u010do uporabo.<\/p>\n<\/div>\n","protected":false},"featured_media":48104,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[11895],"product_tag":[],"class_list":["post-50372","product","type-product","status-publish","has-post-thumbnail","product_cat-susilnik-za-lase","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product\/50372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/comments?post=50372"}],"version-history":[{"count":0,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product\/50372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/media\/48104"}],"wp:attachment":[{"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/media?parent=50372"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product_brand?post=50372"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product_cat?post=50372"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electricsun.de\/sl\/wp-json\/wp\/v2\/product_tag?post=50372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}