{"id":47165,"date":"2025-04-05T11:32:17","date_gmt":"2025-04-05T09:32:17","guid":{"rendered":"https:\/\/electricsun.de\/?post_type=product&#038;p=47165"},"modified":"2025-10-30T11:00:27","modified_gmt":"2025-10-30T09:00:27","slug":"electricsun-camini-elettrici-sonia-rovere-chiaro","status":"publish","type":"product","link":"https:\/\/electricsun.de\/it\/shop\/electricsun-camini-elettrici-sonia-rovere-chiaro\/","title":{"rendered":"ElectricSun camini elettrici SONIA Rovere chiaro camino elettrico, con effetto sonoro, 3 colori, con l\u2019app, L120xH102cm"},"content":{"rendered":"<p><strong>Il ElectricSun SONIA Rovere chiaro camino elettrico<\/strong> presenta una finitura immacolata, completata da colonne classiche che ne esaltano il prestigio.<br \/>\nLe fiamme invitanti creano un&#8217;atmosfera calda, rendendolo un elemento centrale perfetto per qualsiasi spazio abitativo.<br \/>\nGoditi la bellezza di un camino tradizionale con la praticit\u00e0 e la sicurezza della moderna tecnologia elettrica.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Vantaggi ElectricSun camini elettrici SONIA Rovere chiaro camino elettrico:<\/h2>\n<ul>\n<li>Montaggio a pavimento; Montaggio rapido in 20 minuti;<\/li>\n<li>Installazione ideale in qualsiasi luogo: appartamenti, uffici, case, ecc.;<\/li>\n<li>Cornice camino di alta qualit\u00e0 con rinforzi e inserti in legno massello;<\/li>\n<li>Colonne con inserti in legno massello; Design classico &#8211; Tradizionale;<\/li>\n<li>Inserto 23 pollici 58,5 x 44 cm; Potenza 1800W; Tensione 230V;<\/li>\n<li>Effetto fiamma e legna ardente, realistico effetto fiamma;<\/li>\n<li>Effetto fiamma LED: L\u2019effetto fiamma funziona a 10W, utilizzabile indipendentemente dal riscaldamento;<\/li>\n<li>La fiamma ha 3 colori e ha 5 impostazioni di luminosit\u00e0;<\/li>\n<\/ul>\n<h6><img decoding=\"async\" class=\"alignleft size-full wp-image-22195\" title=\"ElectricSun camini elettrici SONIA Rovere chiaro camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/application.svg\" alt=\"ElectricSun camini elettrici SONIA Rovere chiaro camino elettrico\" width=\"40\" height=\"40\" \/>Dispone dell&#8217;applicazione mobile TUYA <img decoding=\"async\" class=\"alignnone size-full wp-image-22195\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/04\/tuya-app.png\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"30px\" \/>o Smart Life <img decoding=\"async\" class=\"alignnone size-full wp-image-22195\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2024\/04\/Smart-Life.png\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"30px\" \/> e comandi vocali con Amazon Alexa <img decoding=\"async\" class=\"alignnone size-full wp-image-22195\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2025\/02\/Amazon-ALEXA.png\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"30px\" \/> e Google Assistant <img decoding=\"async\" class=\"alignnone size-full wp-image-22195\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2025\/02\/GOOGLE-Assistant.png\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"30px\" \/><\/h6>\n<p>Il camino \u00e8 dotato di un modulo Wi-Fi integrato che si collega a Internet tramite il router di casa, per poi essere controllato tramite smartphone o tablet.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft wp-image-3856 size-thumbnail\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/sunet.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Suono<\/h6>\n<p>Dispositivo audio che imita il crepitio dei tronchi e riproduce il suono del fuoco in fiamme che pu\u00f2 essere spento o avviato separatamente dal riscaldamento.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/led.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Tecnologia LED \u2013 basso consumo 10 W<\/h6>\n<p>Tecnologia LED integrata in tutti i camini elettrici ElectricSun.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/afisaj.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Visualizzazione<\/h6>\n<p>\u00c8 controllato dal telecomando o dal pannello di controllo, si illumina e scompare.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/incalzire-termostat.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Riscaldamento con termostato<\/h6>\n<p>Riscaldamento con aerotermo efficiente di alta qualit\u00e0. Termostato di regolazione della temperatura, regolabile 17\u201327\u00b0C. Il camino pu\u00f2 essere utilizzato con o senza calore.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3143\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/efect-flacara.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Effetto fiamma classico<\/h6>\n<p>\u00c8 una tecnologia con il pi\u00f9 vero effetto fiamma classica. La nuova tecnologia offre un&#8217;esperienza utente senza precedenti.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/luminozitate.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Luminosit\u00e0<\/h6>\n<p>Pu\u00f2 impostare e regolare l&#8217;intensit\u00e0 della fiamma in 5 modi diversi, d\u00e0 all&#8217;utente la possibilit\u00e0 di impostare la luminosit\u00e0 perfetta in base all&#8217;atmosfera e alle preferenze.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/speedometer.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Velocit\u00e0<\/h6>\n<p>La fiamma ha una velocit\u00e0 reale.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/telecomanda.svg\" alt=\"ElectricSun camini elettrici SONIA bianco camino elettrico\" width=\"40\" height=\"40\" \/>Telecomando<\/h6>\n<p>Per comodit\u00e0 e controllo delle funzioni.<\/p>\n","protected":false},"featured_media":60092,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[4867],"product_tag":[],"class_list":["post-47165","product","type-product","status-publish","has-post-thumbnail","product_cat-camino-elettrico-camini-moderni","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product\/47165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/comments?post=47165"}],"version-history":[{"count":0,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product\/47165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/media\/60092"}],"wp:attachment":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/media?parent=47165"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_brand?post=47165"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_cat?post=47165"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_tag?post=47165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}