{"id":40341,"date":"2024-03-31T19:15:14","date_gmt":"2024-03-31T17:15:14","guid":{"rendered":"https:\/\/electricsun.de\/?post_type=product&#038;p=40341"},"modified":"2025-10-30T11:00:31","modified_gmt":"2025-10-30T09:00:31","slug":"camino-elettrico-electricsun-paula-vetro-xxs-nero","status":"publish","type":"product","link":"https:\/\/electricsun.de\/it\/shop\/camino-elettrico-electricsun-paula-vetro-xxs-nero\/","title":{"rendered":"Camino elettrico ElectricSun PAULA vetro XXS nero, a parete, a pavimento o incorporabile, 3 colori L76xH45cm"},"content":{"rendered":"<p><strong>Camino elettrico ElectricSun PAULA vetro XXS nero <\/strong> \u00e8 un piccolo camino elettrico che colpisce per il suo design elegante e moderno.<br \/>\nQuesto fantastico camino nero presenta fiamme affascinanti in tre colori vivaci, consentendoti di personalizzare il tuo ambiente senza sforzo.<br \/>\nCon tre accessori inclusi e tre versatili opzioni di installazione, si adatta perfettamente a qualsiasi spazio, rendendolo l&#8217;aggiunta perfetta per esaltare l&#8217;arredamento della tua casa, offrendo al contempo calore e stile.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Vantaggi camino elettrico ElectricSun PAULA vetro XXS nero:<\/h2>\n<ul>\n<li><strong>Ha 3 decorazioni<\/strong>: sassi bianchi, sassolini trasparenti e legno, utilizzabili a piacere.<\/li>\n<li>Dimensioni totale L 76 x H 45 x 16 cm; incasso &#8211; incorporare 680x435x160mm;<\/li>\n<li>Montaggio a parete;<br \/>\nMontaggio-installazione a pavimento o<br \/>\nIncorporabile in mobili, pareti o altri oggetti;<\/li>\n<li>Installazione ideale in qualsiasi luogo: appartamenti, uffici, case, ecc.<\/li>\n<li>Montaggio facile e veloce, consegnato montato;<\/li>\n<li>Qualit\u00e0 premium con schermo in vetro;<\/li>\n<li>Incredibile realismo della fiamma, moderno effetto fiamma, led 10W;<\/li>\n<li>La fiamma funziona indipendentemente dal riscaldamento, con o senza riscaldamento;<\/li>\n<li>La fiamma ha 3 colori giallo\/blu\/giallo+blu e 5 impostazioni di luminosit\u00e0;<\/li>\n<\/ul>\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/led.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\"><\/a>Tecnologia LED &#8211; a basso consumo 10 W<\/h6>\n<p>Tecnologia LED 3D integrata in tutti i caminetti ElectricSun 3D.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/afisaj.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">Schermo<\/h6>\n<p>\u00c8 controllato dal telecomando o dal pannello di controllo, si illumina e scompare.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/incalzire-termostat.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">Riscaldamento del termostato<\/h6>\n<p>Termostato per l&#8217;impostazione della temperatura. Il caminetto pu\u00f2 essere utilizzato con o senza riscaldamento.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3143\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/efect-flacara.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">Effetto fiamma moderno<\/h6>\n<p>\u00c8 stata lanciata la tecnologia con il pi\u00f9 reale e moderno effetto fiamma. La fiamma ha 3 colori. La nuova tecnologia offre un&#8217;esperienza utente senza precedenti.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/luminozitate.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">Luminosit\u00e0<\/h6>\n<p>Pu\u00f2 impostare e regolare l&#8217;intensit\u00e0 della fiamma in 5 modi diversi, offre all&#8217;utente l&#8217;opportunit\u00e0 di impostare la luminosit\u00e0 perfetta in base all&#8217;ambiente e alle preferenze.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/speedometer.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">Velocit\u00e0<\/h6>\n<p>La fiamma ha una velocit\u00e0 reale.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/telecomanda.svg\" alt=\"camino elettrico ElectricSun PAULA vetro piccolo nero\" width=\"40\" height=\"40\">A distanza<\/h6>\n<p>Per comodit\u00e0 e controllo delle funzioni.<\/p>\n","protected":false},"featured_media":33950,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[4867,4868],"product_tag":[],"class_list":["post-40341","product","type-product","status-publish","has-post-thumbnail","product_cat-camino-elettrico-camini-moderni","product_cat-inserto-camino-elettrico","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product\/40341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/comments?post=40341"}],"version-history":[{"count":0,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product\/40341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/media\/33950"}],"wp:attachment":[{"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/media?parent=40341"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_brand?post=40341"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_cat?post=40341"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electricsun.de\/it\/wp-json\/wp\/v2\/product_tag?post=40341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}