{"id":9725,"date":"2018-07-02T13:29:36","date_gmt":"2018-07-02T11:29:36","guid":{"rendered":"https:\/\/electricsun.de\/shop\/cheminee-electrique-murale-paula-moyen-blanche-electricsun\/"},"modified":"2025-10-30T11:00:47","modified_gmt":"2025-10-30T09:00:47","slug":"cheminee-electrique-murale-paula-moyen-blanche-electricsun","status":"publish","type":"product","link":"https:\/\/electricsun.de\/fr\/magasin\/cheminee-electrique-murale-paula-moyen-blanche-electricsun\/","title":{"rendered":"Chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun, avec effet sonore, 10 couleurs, avec App, L120xH46x31cm"},"content":{"rendered":"<p>Moderne et innovante, la <strong>Chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun<\/strong> est le mod\u00e8le pr\u00e9f\u00e9r\u00e9 de nos clients.<br \/>\nLes lignes gracieuses du manteau blanc brillant contrastant avec les plaques lat\u00e9rales l\u00e9g\u00e8rement rustiques conf\u00e8rent au foyer une touche d&rsquo;\u00e9l\u00e9gance et de sophistication.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Avantages chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun:<\/h2>\n<ul>\n<li><strong>Taille moyen L 120 x H 46 x P 31 cm, insert L 65 x H 23 cm;<\/strong><\/li>\n<li>Chemin\u00e9e \u00e9lectrique murale, Chemin\u00e9e \u00e9lectrique blanche;<\/li>\n<li>Installation id\u00e9ale en tout lieu: appartements, bureaux, maisons;<\/li>\n<li>Installation rapide et facile, Livr\u00e9e assembl\u00e9e;<\/li>\n<li>Manteau de qualit\u00e9 sup\u00e9rieure de MDF avec finition blanche;<\/li>\n<li>Avec des assiettes d\u00e9coratives avec deux c\u00f4t\u00e9s, avec lumi\u00e8re du dos ambiante, avec des brindilles d\u00e9coratives et des pierres;<\/li>\n<li>Effet flammes ultra r\u00e9aliste, Effet de flammes moderne;<\/li>\n<li>La flamme LED 10W fonctionne ind\u00e9pendamment du chauffage;<\/li>\n<li>La flamme a 10 couleurs et a 5 r\u00e9glages de luminosit\u00e9;<\/li>\n<\/ul>\n<h6><img class=\"alignleft size-full wp-image-22195\" title=\"Chemin\u00e9e \u00e9lectrique murale ElectricSun PAULA\" src=https:\/\/electricsun.de\/wp-content\/uploads\/2024\/03\/application.svg alt=\"Chemin\u00e9e \u00e9lectrique murale ElectricSun PAULA\" width=\"40\" height=\"40\" \/>Il a l&rsquo;application TUYA <img class=\"alignnone size-full wp-image-22195\" src=https:\/\/electricsun.de\/wp-content\/uploads\/2024\/04\/tuya-app.png alt=\"Chemin\u00e9e \u00e9lectrique murale ElectricSun PAULA\" width=\"30px\" \/>ou Smart Life <img class=\"alignnone size-full wp-image-22195\" src=https:\/\/electricsun.de\/wp-content\/uploads\/2024\/04\/Smart-Life.png alt=\"\" width=\"30px\" \/><\/h6>\n<p>La chemin\u00e9e dispose d&rsquo;un module Wi-Fi int\u00e9gr\u00e9 qui se connecte \u00e0 l&rsquo;Internet via le routeur domestique, apr\u00e8s quoi il est contr\u00f4l\u00e9 depuis un smartphone ou une tablette.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft wp-image-3856 size-thumbnail\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/sunet.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Dispositif sonore int\u00e9gr\u00e9<\/h6>\n<p>Dispositif sonore qui imite le cr\u00e9pitement des billots et reproduit le bruit du feu br\u00fblant qui peut \u00eatre \u00e9teint ou commenc\u00e9 s\u00e9par\u00e9ment du chauffage et a 5 r\u00e9glages.<\/p>\n<h6><img decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/led.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"><\/a> Technologie LED &#8211; faible consommation 10 W<\/h6>\n<p>Technologie LED 3D int\u00e9gr\u00e9e \u00e0 tous les foyers \u00e9lectriques 3D ElectricSun.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/afisaj.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Affichage<\/h6>\n<p>Il est contr\u00f4l\u00e9 par la t\u00e9l\u00e9commande ou le panneau de contr\u00f4le, il s\u2019allume et dispara\u00eet.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/incalzire-termostat.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Chauffage avec thermostat<\/h6>\n<p>Thermostat pour r\u00e9glage de la temp\u00e9rature. La chemin\u00e9e peut \u00eatre utilis\u00e9e avec ou sans chaleur.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-3143\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/efect-flacara.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Effet de flamme moderne<\/h6>\n<p>La technologie a \u00e9t\u00e9 lanc\u00e9e avec l\u2019effet de flamme moderne le plus r\u00e9el. La nouvelle technologie offre une exp\u00e9rience utilisateur sans pr\u00e9c\u00e9dent.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/luminozitate.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Luminosit\u00e9<\/h6>\n<p>Vous pouvez d\u00e9finir et ajuster l\u2019intensit\u00e9 de la flamme de 5 fa\u00e7ons diff\u00e9rentes, donnant \u00e0 l\u2019utilisateur la possibilit\u00e9 de d\u00e9finir la luminosit\u00e9 parfaite en fonction de l\u2019ambiance et des pr\u00e9f\u00e9rences.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/speedometer.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Vitesse<\/h6>\n<p>La flamme a une vraie vitesse.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/lamp.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> Lumi\u00e8re ambiante<\/h6>\n<p>Fournit un effet subtil de lumi\u00e8re de dos pour une ambiance incroyable.<\/p>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" src=\"https:\/\/electricsun.de\/wp-content\/uploads\/2022\/05\/telecomanda.svg\" alt=\"chemin\u00e9e \u00e9lectrique murale Paula moyen blanche ElectricSun\" width=\"40\" height=\"40\"> T\u00e9l\u00e9commande<\/h6>\n<p>Pour plus de commodit\u00e9 et de contr\u00f4le des fonctions.<\/p>\n","protected":false},"featured_media":33144,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[4848],"product_tag":[],"class_list":["post-9725","product","type-product","status-publish","has-post-thumbnail","product_cat-cheminee-electrique","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product\/9725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/comments?post=9725"}],"version-history":[{"count":0,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product\/9725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/media\/33144"}],"wp:attachment":[{"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/media?parent=9725"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product_brand?post=9725"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product_cat?post=9725"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electricsun.de\/fr\/wp-json\/wp\/v2\/product_tag?post=9725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}